{"id":41653,"date":"2022-11-10T00:34:54","date_gmt":"2022-11-10T05:34:54","guid":{"rendered":"https:\/\/www.consoleconnect.com\/cloudrouter-2\/"},"modified":"2024-06-12T08:47:18","modified_gmt":"2024-06-12T12:47:18","slug":"cloudrouter","status":"publish","type":"page","link":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/","title":{"rendered":"CloudRouter\u00ae"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17315&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;hero-banner-bg-img1&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#E8EDEF&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;200&#8243; bottom_padding=&#8221;200&#8243; top_padding_tablet=&#8221;200&#8243; top_padding_phone=&#8221;200&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;page-heading&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1681997119461{margin-bottom: 40px !important;padding-top: 10px !important;}&#8221; el_class=&#8221;page-title&#8221;]\n<h1><span style=\"font-weight: 800; color: #16263f !important;\">Layer 3 <\/span><br \/>\n<span style=\"font-weight: 200; color: #16263f !important;\"> CloudRouter<sup>\u00ae<\/sup><\/span> <img decoding=\"async\" class=\"banner-hrline\" src=\"\/wp-content\/uploads\/2023\/03\/Rectangle-203.svg\" \/><\/h1>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221; el_class=&#8221;page-sub-title&#8221; max_width=&#8221;600&#8243; css=&#8221;.vc_custom_1681205699114{padding-right: 140px !important;padding-bottom: 20px !important;}&#8221;]\n<h3 style=\"text-align: left; color: #16263f !important; font-weight: 400; font-size: 16px; line-height: 28px;\"><span style=\"font-weight: 800 !important;\">Erstellen Sie sofortige virtuelle Netzwerke<\/span> zwischen Ihren verschiedenen Clouds, SaaS-Anwendungen, IoT-Ger\u00e4ten, Unternehmensstandorten, anderen Netzwerken und mehr.<\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;hero-banner-vid-sec&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text el_class=&#8221;video-div&#8221;]<img decoding=\"async\" class=\"vidyard-player-embed\" style=\"width: 100%; margin: auto; display: block;\" src=\"https:\/\/play.vidyard.com\/vvZsWJY9tLbxh1W47LGL6q.jpg\" data-uuid=\"vvZsWJY9tLbxh1W47LGL6q\" data-v=\"4\" data-type=\"inline\" \/>[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;hero-banner-button&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-3&#8243; icon_family=&#8221;default_arrow&#8221; url=&#8221;https:\/\/app.consoleconnect.com\/sign-up\/&#8221; css_animation=&#8221;fadeIn&#8221; margin_top=&#8221;20&#8243; text=&#8221;Registrieren&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17319&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;hero-banner-bg-img2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;0&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][page_submenu alignment=&#8221;center&#8221; sticky=&#8221;true&#8221; bg_color=&#8221;#16263f&#8221; link_color=&#8221;#ffffff&#8221;][page_link link_url=&#8221;#overview&#8221; title=&#8221;\u00dcbersicht&#8221; id=&#8221;1718196423163-0&#8243; tab_id=&#8221;1718196423163-9&#8243;][vc_column_text][\/vc_column_text][\/page_link][page_link title=&#8221;Eigenschaften&#8221; id=&#8221;1718196423272-7&#8243; tab_id=&#8221;1718196423273-5&#8243; link_url=&#8221;#features&#8221;][\/page_link][page_link title=&#8221;Vorteile&#8221; id=&#8221;1718196423345-3&#8243; tab_id=&#8221;1718196423345-3&#8243; link_url=&#8221;#Benefits&#8221;][\/page_link][page_link title=&#8221;Multi-Cloud&#8221; id=&#8221;1718196423425-10&#8243; tab_id=&#8221;1718196423426-8&#8243; link_url=&#8221;#Multi-cloud&#8221;][\/page_link][page_link title=&#8221;Virtuelle Vernetzung&#8221; id=&#8221;1718196423499-7&#8243; tab_id=&#8221;1718196423499-10&#8243; link_url=&#8221;#Network&#8221;][\/page_link][page_link title=&#8221;\u00c4hnliche Dienstleistungen&#8221; id=&#8221;1718196423575-10&#8243; tab_id=&#8221;1718196423575-3&#8243; link_url=&#8221;#Services&#8221;][\/page_link][page_link title=&#8221;Kontakt&#8221; id=&#8221;1718196423649-2&#8243; tab_id=&#8221;1718196423650-7&#8243; link_url=&#8221;#form&#8221;][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;cloud-ebook-section&#8221; id=&#8221;overview&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;0&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; bottom_margin=&#8221;0&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17190&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;cloud-ebook-img&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; top_margin=&#8221;120px&#8221; top_margin_tablet=&#8221;20px&#8221; bottom_margin_tablet=&#8221;80px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css=&#8221;.vc_custom_1705662872809{padding-bottom: 20px !important;}&#8221;]\n<p style=\"color: #16263f !important; padding-bottom: 10px;\"><span style=\"font-size: 20px; line-height: 37px;\">Beseitigen Sie den Aufwand und die Komplexit\u00e4t der Netzwerkkonfiguration und -verwaltung.<\/span><\/p>\n<p style=\"color: #16263f !important;\"><span style=\"font-size: 20px; line-height: 37px;\">Verwenden Sie CloudRouter<sup>\u00ae<\/sup>, um ein privates und sicheres Layer-3-Netzwerk zwischen Ihren verschiedenen Netzwerkendpunkten zu schaffen.<\/span><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17349&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;hero-banner-bg-img3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80px&#8221; bottom_padding=&#8221;60px&#8221; bottom_padding_tablet=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;features&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;45434&#8243; animation=&#8221;Fade In From Bottom&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;small-icon-text iconL-textR&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h2 style=\"text-align: left; font-size: 30px; text-transform: none;\">Warum <span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\"><span style=\"font-weight: 400 !important;\">CloudRouter<sup>\u00ae<\/sup><\/span><\/span><br \/>\nf\u00fcr Sie geeignet ist<\/h2>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1681856880993{padding-bottom: 40px !important;}&#8221;]\n<p style=\"text-align: left;\"><span style=\"font-size: 14px;\">Erleben Sie globales virtuelles Routing in einem der gr\u00f6\u00dften Hochleistungsnetze der Welt.<\/span><\/p>\n[\/vc_column_text]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/round-triangle_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Privat und sicher<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 40px;\"><span style=\"font-size: 14px;\">Verbindungen zwischen Clouds \u2013 ohne die Notwendigkeit, Ger\u00e4te zu installieren, zu verwalten oder zu warten.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/semi-circle_grad-2_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Zeigen, klicken, verbinden<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 40px;\"><span style=\"font-size: 14px;\">F\u00fcgen Sie neue Netzwerk-Edge-Standorte hinzu oder entfernen Sie sie \u2013 CloudRouter<sup>\u00ae<\/sup> erledigt den Rest.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/circle_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Flexible Bandbreite on-demand<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 40px;\"><span style=\"font-size: 14px;\">Spin-up-Dienste ab nur einer Stunde.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/hexagon_grad-2_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">W\u00e4hlen Sie Ihre Serviceklasse<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 40px;\"><span style=\"font-size: 14px;\">Priorisieren Sie den Datenverkehr f\u00fcr Ihre unternehmenskritischen Anwendungen.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2023\/01\/lead-purple@2x-300x300.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Erweitertes und dynamisches Routing<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 40px;\"><span style=\"font-size: 14px;\">Erstellen Sie ein virtuelles \u201eFull Mesh\u201c zwischen Ihren verschiedenen Netzendpunkten.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;desktop-display-block&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17508&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;why-cloud-router-bg-img&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;90&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;features&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;20&#8243; text_align=&#8221;left&#8221; el_id=&#8221;features&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h2 style=\"text-align: center; font-size: 30px; text-transform: none;\">Warum <span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\"><span style=\"font-weight: 400 !important;\"><sup>CloudRouter\u00ae<\/sup><\/span><\/span> f\u00fcr Sie geeignet ist<\/h2>\n[\/vc_column_text][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<p style=\"text-align: center;\">Erleben Sie globales virtuelles Routing in einem der gr\u00f6\u00dften Hochleistungsnetze der Welt.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;50px&#8221; bottom_padding=&#8221;20px&#8221; text_align=&#8221;center&#8221;][vc_column_inner column_padding=&#8221;padding-7-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17166&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_bottom=&#8221;25&#8243;][vc_custom_heading text=&#8221;Privat und sicher&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:center|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:https%3A%2F%2Fdev-consoleconnect-global.devdomain.biz%2Fservices%2Fautomated-services%2F|title:IoT||&#8221;][vc_column_text]Verbindungen zwischen Clouds \u2013 ohne Ger\u00e4te installieren, verwalten oder warten zu m\u00fcssen.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-7-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17167&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_bottom=&#8221;25&#8243;][vc_custom_heading text=&#8221;Zeigen, klicken, verbinden&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:center|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:https%3A%2F%2Fdev-consoleconnect-global.devdomain.biz%2Fservices%2Fautomated-services%2F|title:IoT||&#8221;][vc_column_text]Verwenden Sie das Console Connect-Verwaltungsportal, um neue Netzwerk-Edge-Standorte hinzuzuf\u00fcgen oder zu entfernen, und lassen Sie <sup>CloudRouter\u00ae<\/sup> den Rest erledigen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;50px&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17172&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_bottom=&#8221;25&#8243;][vc_custom_heading text=&#8221;Flexible Bandbreite on-demand&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:center|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:https%3A%2F%2Fdev-consoleconnect-global.devdomain.biz%2Fservices%2Fautomated-services%2F|title:IoT||&#8221;][vc_column_text]Spin-up-Dienste ab nur einer Stunde.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17173&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_bottom=&#8221;25&#8243;][vc_custom_heading text=&#8221;W\u00e4hlen Sie Ihre Serviceklasse&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:center|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:https%3A%2F%2Fdev-consoleconnect-global.devdomain.biz%2Fservices%2Fautomated-services%2F|title:IoT||&#8221;][vc_column_text]Priorisieren Sie den Datenverkehr f\u00fcr Ihre unternehmenskritischen Anwendungen.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#16263f&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17174&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_bottom=&#8221;25&#8243;][vc_custom_heading text=&#8221;Erweitertes und dynamisches Routing&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:center|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:https%3A%2F%2Fdev-consoleconnect-global.devdomain.biz%2Fservices%2Fautomated-services%2F|title:IoT||&#8221;][vc_column_text]Erstellen Sie ein virtuelles \u201eFull Mesh\u201c zwischen Ihren verschiedenen Netzendpunkten.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;18570&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;benefits-bg-img&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#E8EDEF&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;Benefits&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner disable_element=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;16420&#8243; animation=&#8221;Fade In From Bottom&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;120&#8243; bottom_padding=&#8221;20&#8243; top_padding_tablet=&#8221;60&#8243; text_align=&#8221;left&#8221; el_id=&#8221;Benefits&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<h2 style=\"font-size: 30px; text-transform: none;\">Vorteile von <span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\"><span style=\"font-weight: 400 !important;\"> CloudRouter<sup>\u00ae<\/sup><\/span><\/span><\/h2>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;small-icon-text iconL-textR&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/round-triangle_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Effizienteres Routing<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 56px;\"><span style=\"font-size: 14px;\">Vermeiden Sie das Backhauling Ihres NetzwerkTraffics zwischen Datenzentren und der Cloud.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/semi-circle_grad-2_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Das volle Cloud-Erlebnis<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 30px;\"><span style=\"font-size: 14px;\">CloudRouter<sup>\u00ae<\/sup> bietet Ihnen die M\u00f6glichkeit, Daten zwischen Clouds innerhalb Ihres eigenen virtuellen Layer-3-Netzwerks zu \u00fcbertragen, ohne dass Sie einen physischen Access Port in einem Datenzentrum ben\u00f6tigen.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/star_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Leistungsstark<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f;\"><span style=\"font-size: 14px;\">CloudRouter<sup>\u00ae<\/sup> nutzt das eigene private Hochleistungsnetzwerk von Console Connect und erm\u00f6glicht es Benutzern, aus verschiedenen Serviceklassen zu w\u00e4hlen.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;small-icon-text iconL-textR&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/hexagon_grad-2_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Einfache Einrichtung<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 52px;\"><span style=\"font-size: 14px;\">Sie m\u00fcssen Ihren Standort nur einmal konfigurieren und CloudRouter<sup>\u00ae<\/sup> erstellt ein virtuelles Netz zwischen all Ihren anderen Netzwerkendpunkten.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/circle_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Wirklich globale Reichweite<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f; padding-bottom: 54px;\"><span style=\"font-size: 14px;\">Umfassende Reichweite bei allen gro\u00dfen Cloud-Anbietern und einer wachsenden Zahl von SaaS-Partnern mit einer Auswahl von mehr als 150 Partner-Onramps weltweit.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/11\/right-triangle_grad-2_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"text-align: left; color: #16263f; font-size: 16px; font-weight: 800; margin-bottom: 10px !important;\"><span style=\"font-size: 14px;\">Sie haben die volle Kontrolle<\/span><\/h4>\n<p style=\"text-align: left; color: #16263f;\"><span style=\"font-size: 14px;\">Richten Sie eine virtuelle Netzwerkverbindung ab nur einem Tag ein und verwalten Sie die Gesamtbandbreite Ihrer CloudRouter<sup>\u00ae<\/sup>(oder Router) \u00fcber die Console Connect App.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;55&#8243; bottom_padding=&#8221;25&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-3&#8243; icon_family=&#8221;default_arrow&#8221; text=&#8221;Weitere Informationen zu <b>CloudRouter<sup>\u00ae<\/sup><\/b> herunterladen&#8221; url=&#8221;https:\/\/info.consoleconnect.com\/resources\/cloudrouter-data-sheet&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17601&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;benefits-bg-img2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;h-tabs-section&#8221; id=&#8221;Multi-cloud&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;40px&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h2 style=\"text-align: center; font-size: 30px; text-transform: none;\"><span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\">Cloud-Konnektivit\u00e4t <\/span>einfach halten<\/h2>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1705663030224{padding-bottom: 20px !important;}&#8221;]\n<h3 style=\"text-align: center; color: #16263f !important; font-weight: 400; font-size: 16px; line-height: 28px;\">Die Umstellung auf Multi-Cloud kann komplex sein, aber CloudRouter<sup>\u00ae<\/sup> macht Ihre Cloud-Konnektivit\u00e4t <span style=\"font-weight: 800 !important;\">einfach<\/span>.<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1681997698593{padding-bottom: 20px !important;}&#8221;]\n<h3 style=\"text-align: center; color: #16263f !important; font-weight: 400; font-size: 16px; line-height: 28px;\"><span style=\"font-weight: 800 !important;\">Verbinden Sie <\/span>eine beliebige Cloud mit einer beliebigen Cloud oder eine beliebige Cloud mit einem beliebigen Standort \u2013 ganz ohne dedizierte Hardware.<\/h3>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column_inner][\/vc_row_inner][tabbed_section style=&#8221;material&#8221; alignment=&#8221;center&#8221; spacing=&#8221;side-40px&#8221; tab_color=&#8221;Accent-Color&#8221; icon_size=&#8221;24&#8243; el_class=&#8221;cloud-tab-sec1&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Multi-Cloud-Umgebungen&#8221; id=&#8221;1718196424436-10&#8243; tab_id=&#8221;1718196424436-7&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;120&#8243; right_padding_desktop=&#8221;120&#8243; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; text_align=&#8221;left&#8221; class=&#8221;tab-section-content&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<div class=\"multi-cloud-ul\">\n<div class=\"multi-cloud-left\"><span style=\"font-size: 14px;\">Verbindung zwischen verschiedenen Cloud-Regionen.<\/span><\/div>\n<div class=\"multi-cloud-right\"><span style=\"font-size: 14px;\">Verbindung zwischen verschiedenen Cloud-Plattformen.<\/span><\/div>\n<\/div>\n[\/vc_column_text][image_with_animation image_url=&#8221;21399&#8243; animation=&#8221;Fade In From Left&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Hybride Cloud-Umgebung&#8221; id=&#8221;1718196424544-2&#8243; tab_id=&#8221;1718196424544-0&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;120&#8243; right_padding_desktop=&#8221;120&#8243; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; text_align=&#8221;left&#8221; class=&#8221;tab-section-content&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<div class=\"multi-cloud-ul\">\n<div class=\"multi-cloud-left\"><span style=\"font-size: 14px;\">Richten Sie einen Access Port ein und verbinden Sie Ihre Unternehmensrechenzentren und Standorte mit Ihrer Multi-Cloud-Umgebung.<\/span><\/div>\n<div class=\"multi-cloud-right\"><span style=\"font-size: 14px;\">Verschieben Sie den Datenverkehr zwischen Ihrem privaten WAN und der Cloud.<\/span><\/div>\n<\/div>\n[\/vc_column_text][image_with_animation image_url=&#8221;21400&#8243; animation=&#8221;Fade In From Left&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Backup und Rendundanz&#8221; id=&#8221;1718196424649-7&#8243; tab_id=&#8221;1718196424650-6&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;20&#8243; left_padding_desktop=&#8221;120&#8243; right_padding_desktop=&#8221;120&#8243; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; text_align=&#8221;left&#8221; class=&#8221;tab-section-content&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<div class=\"multi-cloud-ul\">\n<div class=\"multi-cloud-left\"><span style=\"font-size: 14px;\">Automatisieren Sie Ihre Datensicherung und -wiederherstellung zwischen Clouds mit zuverl\u00e4ssiger und redundanter Konnektivit\u00e4t.<\/span><\/div>\n<div class=\"multi-cloud-right\"><span style=\"font-size: 14px;\">Ideal f\u00fcr Unternehmen, die Prim\u00e4rsysteme auf einer Cloud-Plattform und Backup- oder Sekund\u00e4rsysteme auf einer anderen betreiben.<\/span><\/div>\n<\/div>\n[\/vc_column_text][image_with_animation image_url=&#8221;21407&#8243; animation=&#8221;Fade In From Left&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text][\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;SaaS-\u00d6kosysteme&#8221; id=&#8221;1718196424764-10&#8243; tab_id=&#8221;1718196424764-9&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;20&#8243; left_padding_desktop=&#8221;120&#8243; right_padding_desktop=&#8221;120&#8243; left_padding_tablet=&#8221;0&#8243; right_padding_tablet=&#8221;0&#8243; text_align=&#8221;left&#8221; class=&#8221;tab-section-content&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<div class=\"multi-cloud-ul\">\n<div class=\"multi-cloud-left\"><span style=\"font-size: 14px;\">Verbessern Sie die Performance Ihrer Anwendungen mit privaten Verbindungen zu Ihrem SaaS-Anbieter.<\/span><\/div>\n<div class=\"multi-cloud-right\"><span style=\"font-size: 14px;\">Nutzen Sie CloudRouter<sup>\u00ae<\/sup>, um sichere und schnelle Verbindungen zu mehreren SaaS-Anbietern herzustellen.<\/span><\/div>\n<\/div>\n[\/vc_column_text][image_with_animation image_url=&#8221;21408&#8243; animation=&#8221;Fade In From Left&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text][\/vc_column_text][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;bottom&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-3&#8243; color_override=&#8221;#ff276f&#8221; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; url=&#8221;\/de\/clouds\/&#8221; text=&#8221;Entdecken Sie, welche Clouds auf <b>Console Connect <\/b> verf\u00fcgbar sind&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#16263f&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;cloud-ebook-section&#8221; id=&#8221;Multi-cloud&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; top_padding=&#8221;60&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;small-icon-text iconL-textR&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h2 style=\"font-size: 22px; text-transform: none; line-height: 35px; margin-bottom: 5px !important;\">Laden Sie unser E-Book herunter zum Thema:<\/h2>\n<h2 class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 22px; text-transform: none; line-height: 35px; margin-bottom: 10px !important;\">So halten Sie Ihr- Multi-Cloud-<br \/>\nUmfeld einfach<\/h2>\n<p style=\"padding-bottom: 20px;\"><b>Mit folgenden Lerninhalten:<\/b><\/p>\n[\/vc_column_text]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/10\/hexagon_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"font-weight: 300; padding-bottom: 30px;\"><span style=\"font-size: 14px;\">Verbessern Sie die Daten\u00fcbertragung zwischen Clouds<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/10\/hexagon_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"font-weight: 300; padding-bottom: 30px;\"><span style=\"font-size: 14px;\">Vermeiden Sie h\u00e4ufige Fallstricke bei der regions\u00fcbergreifenden Daten\u00fcbertragung<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/10\/hexagon_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"font-weight: 300;\"><span style=\"font-size: 14px;\">Automatisieren Sie Ihre Datensicherung und -wiederherstellung<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_tablet=&#8221;50&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17039&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;cloud-ebook-img&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;padding-1-percent&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; bottom_margin_tablet=&#8221;40px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;e-book-btn&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][nectar_btn size=&#8221;jumbo&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#0098ff&#8221; solid_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;E-Buch herunterladen&#8221; url=&#8221;https:\/\/info.consoleconnect.com\/resources\/multi-cloud-connectivity-challenges?hsLang=en&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;30&#8243; bottom_padding=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;Network&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; bottom_margin=&#8221;0&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;small-icon-text iconL-textR&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css=&#8221;.vc_custom_1668401335389{padding-bottom: 10px !important;}&#8221;]\n<h2 style=\"font-size: 30px; text-transform: none;\">Ein <span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\">virtuelles globales Netzwerk<\/span><br \/>\nimmer zur Hand<\/h2>\n[\/vc_column_text]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/10\/hexagon_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"padding-bottom: 30px;\"><span style=\"font-size: 14px;\">Bauen Sie ein virtuelles Netzwerk \u00fcber eines der gr\u00f6\u00dften Hochleistungsnetzwerke der Welt auf.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/10\/hexagon_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"padding-bottom: 30px;\"><span style=\"font-size: 14px;\">Erweitern Sie Ihre Netzwerkumgebung, ohne sich um zus\u00e4tzliche Netzwerkkonfiguration und -verwaltung k\u00fcmmern zu m\u00fcssen.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/10\/hexagon_grad-1_300dpi.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"padding-bottom: 30px;\"><span style=\"font-size: 14px;\">Verbinden Sie per Mausklick Ihre Clouds, SaaS-Anwendungen, Unternehmensstandorte, IoT-Ger\u00e4te und andere Netzwerke, einschlie\u00dflich Datenzentren, Wide Area Networks (WAN) und Last-Mile-Zugang.<\/span><\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin=&#8221;0&#8243; right_margin=&#8221;0&#8243; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17218&#8243; animation=&#8221;Fade In From Right&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;20&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]<em><span style=\"font-size: 12px;\">Ein Console Connect <a href=\"\/de\/services\/access-ports\/\">Access Port<\/a> ist erforderlich, um Ihre Unternehmensstandorte und Netzwerke mit CloudRouter<sup>\u00ae<\/sup> hinzuzuf\u00fcgen.<\/span><\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f7f9f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;30&#8243; bottom_padding=&#8221;20&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;16423&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;30&#8243; bottom_padding=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; animate=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;related-service&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; class=&#8221;related-service-bg-img&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17213&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;20&#8243; top_padding_tablet=&#8221;120&#8243; bottom_padding_tablet=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;related-service&#8221; id=&#8221;Services&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; top_margin_tablet=&#8221;20px&#8221; right_margin_tablet=&#8221;135px&#8221; top_margin_phone=&#8221;30px&#8221; right_margin_phone=&#8221;25px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;access-port-title&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<h2 style=\"font-size: 30px; text-transform: none;\">Mehr Leistung \u00fcber einen einzigen <span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\">Access Port<\/span><\/h2>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;60&#8243; text_align=&#8221;left&#8221; class=&#8221;access-port-icon-section&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;21028&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_custom_heading text=&#8221;Zusammenschaltung (Layer 2)&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:left|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:%2Fde%2Fservices%2Flayer-2%2F|title:Interconnection%20(Layer%202)||&#8221;][vc_column_text]\n<p style=\"text-align: left;\"><span style=\"font-size: 14px; padding-bottom: 56;\">Von globalen Datenzentren, Cloud, Anwendungen, Gesch\u00e4ftspartnern, Internet Exchanges und mehr.<\/span><\/p>\n[\/vc_column_text][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;p&#8221; text_color=&#8221;#ff276f&#8221; button_color=&#8221;default&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; display=&#8221;block&#8221; margin_top=&#8221;44&#8243; url=&#8221;\/de\/services\/layer-2\/&#8221; link_text=&#8221;<b>Mehr lesen<\/b>&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;18623&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_custom_heading text=&#8221;Internet der Dinge&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:left|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:%2Fde%2Fservices%2Fiot%2F|title:IoT||&#8221;][vc_column_text]\n<p style=\"text-align: left;\"><span style=\"font-size: 14px;\">Globale IoT-Konnektivit\u00e4t vom Edge bis zur Cloud, alles verwaltet und orchestriert von der Console Connect-Plattform.<\/span><\/p>\n[\/vc_column_text][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;p&#8221; text_color=&#8221;#ff276f&#8221; button_color=&#8221;default&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; display=&#8221;block&#8221; margin_top=&#8221;20&#8243; url=&#8221;\/de\/services\/iot\/&#8221; link_text=&#8221;<b>Mehr lesen<\/b>&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;18619&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_custom_heading text=&#8221;Internet on-demand&#8221; font_container=&#8221;tag:h4|font_size:16px|text_align:left|color:%2316263f&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:700%20bold%20regular%3A700%3Anormal&#8221; link=&#8221;url:%2Fde%2Fservices%2Finternet-on-demand%2F|title:Internet%20On-Demand||&#8221;][vc_column_text]\n<p style=\"text-align: left;\"><span style=\"font-size: 14px;\">Greifen Sie auf unseren branchenf\u00fchrenden IP-Transit-Service zu, der \u00fcber unser globales IP-Netz bereitgestellt wird \u2013 wann immer Sie ihn ben\u00f6tigen.<\/span><\/p>\n[\/vc_column_text][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;p&#8221; text_color=&#8221;#ff276f&#8221; button_color=&#8221;default&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; display=&#8221;block&#8221; margin_top=&#8221;20&#8243; url=&#8221;\/de\/services\/internet-on-demand\/&#8221; link_text=&#8221;<b>Mehr lesen<\/b>&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17288&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;form-section-bg-img1&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;form-section-animation&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]<div id=\"anim-6a574c3196089\" class=\"wpbdmv-animation align-left renderer-svg  \" style=\"max-width: 100%;\"><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; left_padding_tablet=&#8221;100&#8243; right_padding_tablet=&#8221;100&#8243; left_padding_phone=&#8221;20&#8243; right_padding_phone=&#8221;20&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; top_margin=&#8221;50px&#8221; bottom_margin=&#8221;50px&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;large_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css=&#8221;.vc_custom_1682542401561{padding-top: 50px !important;padding-bottom: 40px !important;}&#8221;]\n<h2 style=\"font-size: 30px; text-transform: none; text-align: center;\">Reden wir dar\u00fcber, wie <span class=\"gradient-text\" style=\"font-weight: bold !important; font-size: 30px;\">Layer 3<\/span><br \/>\nf\u00fcr Ihr Unternehmen arbeiten kann<\/h2>\n[\/vc_column_text][vc_raw_html css=&#8221;.vc_custom_1682542363743{padding-bottom: 50px !important;}&#8221; el_class=&#8221;cloudrouter-form&#8221;]JTNDJTIxLS0lNUJpZiUyMGx0ZSUyMElFJTIwOCU1RCUzRSUwQSUzQ3NjcmlwdCUyMGNoYXJzZXQlM0QlMjJ1dGYtOCUyMiUyMHR5cGUlM0QlMjJ0ZXh0JTJGamF2YXNjcmlwdCUyMiUyMHNyYyUzRCUyMiUyRiUyRmpzLmhzZm9ybXMubmV0JTJGZm9ybXMlMkZ2Mi1sZWdhY3kuanMlMjIlM0UlM0MlMkZzY3JpcHQlM0UlMEElM0MlMjElNUJlbmRpZiU1RC0tJTNFJTBBJTNDc2NyaXB0JTIwY2hhcnNldCUzRCUyMnV0Zi04JTIyJTIwdHlwZSUzRCUyMnRleHQlMkZqYXZhc2NyaXB0JTIyJTIwc3JjJTNEJTIyJTJGJTJGanMuaHNmb3Jtcy5uZXQlMkZmb3JtcyUyRnYyLmpzJTIyJTNFJTNDJTJGc2NyaXB0JTNFJTBBJTNDc2NyaXB0JTNFJTBBJTIwJTIwaGJzcHQuZm9ybXMuY3JlYXRlJTI4JTdCJTBBJTA5cmVnaW9uJTNBJTIwJTIybmExJTIyJTJDJTBBJTA5cG9ydGFsSWQlM0ElMjAlMjIzMDc2MjAzJTIyJTJDJTBBJTA5Zm9ybUlkJTNBJTIwJTIyYzZiMDcyMjEtNzQxZi00YzRmLTgwNjgtY2EzZDQxNjE2MmE4JTIyJTBBJTdEJTI5JTNCJTBBJTNDJTJGc2NyaXB0JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;1&#8243; id=&#8221;form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;17293&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;form-section-bg-img2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#16263f&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;100&#8243; top_padding_tablet=&#8221;190&#8243; bottom_padding_tablet=&#8221;190&#8243; top_padding_phone=&#8221;230&#8243; bottom_padding_phone=&#8221;230&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;top-footer&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_b_to_right_t&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;top-footer-content-wrap&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;10\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_custom_heading text=&#8221;Das bekommen Sie&#8221; font_container=&#8221;tag:h2|font_size:30px|text_align:center&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; bottom_padding=&#8221;6&#8243; bottom_padding_tablet=&#8221;0&#8243; bottom_padding_phone=&#8221;0&#8243; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;footer-top-listing&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/12\/star_grad-1_300dpi@2x.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"text-align: left;\">Nutzen Sie unseren Preiskalkulator f\u00fcr Ports und virtuelle Verbindungen<\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/12\/hexagon_grad-2_300dpi@2x.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"text-align: left;\">Sehen Sie, welche Clouds, SaaS und Unternehmen Teil unserer Community sind<\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;footer-top-listing&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/12\/right-triangle_grad-2_300dpi@2x.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"text-align: left;\">Verbindung und Zusammenarbeit mit Partnern und Kunden in unserer Gemeinschaft<\/p>\n <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2022\/12\/circle_grad-1_300dpi@2x.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<p style=\"text-align: left;\">Registrieren Sie Ihr Unternehmen f\u00fcr private Self-Service-Konnektivit\u00e4t on-demand<\/p>\n <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-3&#8243; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/app.consoleconnect.com\/sign-up\/&#8221; text=&#8221;ANMELDEN&#8221; margin_top=&#8221;25&#8243; margin_bottom=&#8221;10&#8243;][vc_column_text el_class=&#8221;small-text&#8221;]Sie sind bereits Mitglied?<strong> <a href=\"https:\/\/app.consoleconnect.com\/home\" target=\"_blank\" rel=\"noopener noreferrer\">Melden Sie sich an<\/a><\/strong>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#16263f&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; bottom_padding=&#8221;60&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; id=&#8221;Register&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_b_to_right_t&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; css=&#8221;.vc_custom_1587541204006{border-radius: 3px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-left&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css=&#8221;.vc_custom_1587541494384{padding-bottom: 20px !important;}&#8221;]\n<h4 class=\"white\">JETZT REGISTRIEREN<\/h4>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-3&#8243; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/app.consoleconnect.com\/sign-up\/&#8221; text=&#8221;ANMELDEN&#8221; margin_top=&#8221;10&#8243; margin_bottom=&#8221;1&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text]Sie sind bereits Mitglied? <a href=\"https:\/\/app.consoleconnect.com\/home\" target=\"_blank\" rel=\"noopener noreferrer\">Anmelden<\/a>.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;what-you-get&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text css=&#8221;.vc_custom_1587541500603{margin-bottom: 20px !important;}&#8221;]\n<h4 class=\"white\">Das bekommen Sie<\/h4>\n[\/vc_column_text]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-white.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Nutzen Sie unseren Preiskalkulator f\u00fcr Ports und virtuelle Verbindungen <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-white.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Sehen Sie, welche Clouds, SaaS und Unternehmen Teil unserer Community sind <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-white.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Verbinden Sie sich mit Partnern und Kunden und arbeiten Sie mit ihnen zusammen <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-white.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Registrieren Sie Ihr Unternehmen f\u00fcr private Self-Service-Konnektivit\u00e4t on-demand <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#00498f&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-green.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Zwischen mehr als 750 Rechenzentren in \u00fcber 50 L\u00e4ndern. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-green.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Direkte Verbindungen zu allen wichtigen Cloud-Anbietern. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-green.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Weitere Gesch\u00e4ftspartner und Dienstanbieter auf der Console Connect-Plattform. <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2020\/07\/bullet-tick-iso-green.svg\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> Remote-Peering an den gr\u00f6\u00dften Internet Exchanges der Welt <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]\n<div id=\"excerpt\" class=\"memsource-post-attribute\">\n<div class=\"memsource-post-attribute-end\"><\/div>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e8edef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":29,"featured_media":44388,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","phrase_has_initial_content_push":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-41653","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CloudRouter\u00ae \u2013 Console Connect<\/title>\n<meta name=\"description\" content=\"Erhalten Sie nahtlose Cloud-Konnektivit\u00e4t mit unserem Layer 3 Cloud Router. Erstellen Sie sichere, private Netzwerke und vereinfachen Sie die Verwaltung Ihres layer-3-Netzwerks, indem Sie hier klicken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CloudRouter\u00ae \u2013 Console Connect\" \/>\n<meta property=\"og:description\" content=\"CloudRouter bietet Ihnen einen hochleistungsf\u00e4higen, privaten Datentransfer zwischen allen f\u00fchrenden Hyperscale-Cloud-Anbietern in mehreren globalen Regionen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/\" \/>\n<meta property=\"og:site_name\" content=\"Console Connect\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ConsoleConnectInc\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T12:47:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2024\/04\/Cloud-Router-DE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"802\" \/>\n\t<meta property=\"og:image:height\" content=\"843\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"CloudRouter\u00ae \u2013 Console Connect\" \/>\n<meta name=\"twitter:description\" content=\"CloudRouter bietet Ihnen einen hochleistungsf\u00e4higen, privaten Datentransfer zwischen allen f\u00fchrenden Hyperscale-Cloud-Anbietern in mehreren globalen Regionen.\" \/>\n<meta name=\"twitter:site\" content=\"@ConsoleConnect\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"57 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/\",\"url\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/\",\"name\":\"CloudRouter\u00ae \u2013 Console Connect\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.consoleconnect.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Cloud-Router-DE.png\",\"datePublished\":\"2022-11-10T05:34:54+00:00\",\"dateModified\":\"2024-06-12T12:47:18+00:00\",\"description\":\"Erhalten Sie nahtlose Cloud-Konnektivit\u00e4t mit unserem Layer 3 Cloud Router. Erstellen Sie sichere, private Netzwerke und vereinfachen Sie die Verwaltung Ihres layer-3-Netzwerks, indem Sie hier klicken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.consoleconnect.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Cloud-Router-DE.png\",\"contentUrl\":\"https:\\\/\\\/www.consoleconnect.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Cloud-Router-DE.png\",\"width\":802,\"height\":843},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/cloudrouter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consoleconnect.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CloudRouter\u00ae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/#website\",\"url\":\"https:\\\/\\\/www.consoleconnect.com\\\/\",\"name\":\"Console Connect by PCCW Global\",\"description\":\"Software-Defined Interconnection made easy\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consoleconnect.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/#organization\",\"name\":\"Console Connect by PCCW Global\",\"url\":\"https:\\\/\\\/www.consoleconnect.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consoleconnect.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo-with-wordmark-by-PCCW.svg\",\"contentUrl\":\"https:\\\/\\\/www.consoleconnect.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/logo-with-wordmark-by-PCCW.svg\",\"width\":1,\"height\":1,\"caption\":\"Console Connect by PCCW Global\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consoleconnect.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ConsoleConnectInc\",\"https:\\\/\\\/x.com\\\/ConsoleConnect\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/console-inc-\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CloudRouter\u00ae \u2013 Console Connect","description":"Erhalten Sie nahtlose Cloud-Konnektivit\u00e4t mit unserem Layer 3 Cloud Router. Erstellen Sie sichere, private Netzwerke und vereinfachen Sie die Verwaltung Ihres layer-3-Netzwerks, indem Sie hier klicken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/","og_locale":"de_DE","og_type":"article","og_title":"CloudRouter\u00ae \u2013 Console Connect","og_description":"CloudRouter bietet Ihnen einen hochleistungsf\u00e4higen, privaten Datentransfer zwischen allen f\u00fchrenden Hyperscale-Cloud-Anbietern in mehreren globalen Regionen.","og_url":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/","og_site_name":"Console Connect","article_publisher":"https:\/\/www.facebook.com\/ConsoleConnectInc","article_modified_time":"2024-06-12T12:47:18+00:00","og_image":[{"width":802,"height":843,"url":"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2024\/04\/Cloud-Router-DE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"CloudRouter\u00ae \u2013 Console Connect","twitter_description":"CloudRouter bietet Ihnen einen hochleistungsf\u00e4higen, privaten Datentransfer zwischen allen f\u00fchrenden Hyperscale-Cloud-Anbietern in mehreren globalen Regionen.","twitter_site":"@ConsoleConnect","twitter_misc":{"Est. reading time":"57 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/","url":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/","name":"CloudRouter\u00ae \u2013 Console Connect","isPartOf":{"@id":"https:\/\/www.consoleconnect.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/#primaryimage"},"image":{"@id":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2024\/04\/Cloud-Router-DE.png","datePublished":"2022-11-10T05:34:54+00:00","dateModified":"2024-06-12T12:47:18+00:00","description":"Erhalten Sie nahtlose Cloud-Konnektivit\u00e4t mit unserem Layer 3 Cloud Router. Erstellen Sie sichere, private Netzwerke und vereinfachen Sie die Verwaltung Ihres layer-3-Netzwerks, indem Sie hier klicken.","breadcrumb":{"@id":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consoleconnect.com\/de\/cloudrouter\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/#primaryimage","url":"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2024\/04\/Cloud-Router-DE.png","contentUrl":"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2024\/04\/Cloud-Router-DE.png","width":802,"height":843},{"@type":"BreadcrumbList","@id":"https:\/\/www.consoleconnect.com\/de\/cloudrouter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consoleconnect.com\/de\/"},{"@type":"ListItem","position":2,"name":"CloudRouter\u00ae"}]},{"@type":"WebSite","@id":"https:\/\/www.consoleconnect.com\/#website","url":"https:\/\/www.consoleconnect.com\/","name":"Console Connect by PCCW Global","description":"Software-Defined Interconnection made easy","publisher":{"@id":"https:\/\/www.consoleconnect.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consoleconnect.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.consoleconnect.com\/#organization","name":"Console Connect by PCCW Global","url":"https:\/\/www.consoleconnect.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.consoleconnect.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2018\/03\/logo-with-wordmark-by-PCCW.svg","contentUrl":"https:\/\/www.consoleconnect.com\/wp-content\/uploads\/2018\/03\/logo-with-wordmark-by-PCCW.svg","width":1,"height":1,"caption":"Console Connect by PCCW Global"},"image":{"@id":"https:\/\/www.consoleconnect.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ConsoleConnectInc","https:\/\/x.com\/ConsoleConnect","https:\/\/www.linkedin.com\/company\/console-inc-\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/pages\/41653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/comments?post=41653"}],"version-history":[{"count":14,"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/pages\/41653\/revisions"}],"predecessor-version":[{"id":45444,"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/pages\/41653\/revisions\/45444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/media\/44388"}],"wp:attachment":[{"href":"https:\/\/www.consoleconnect.com\/de\/wp-json\/wp\/v2\/media?parent=41653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}